{"id":117273,"date":"2019-09-01T06:47:32","date_gmt":"2019-09-01T06:47:32","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-marruecos-en-dijon-francia\/"},"modified":"2019-09-01T06:47:32","modified_gmt":"2019-09-01T06:47:32","slug":"consulado-general-de-marruecos-en-dijon-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-marruecos-en-dijon-francia\/","title":{"rendered":"Consulado General de Marruecos en Dijon, Francia"},"content":{"rendered":"<div id=\"trave-3912664232\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado marroqu\u00ed en Dijon, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n26, Rue Louis de Broglie<br \/>\nB.P.79<br \/>\n21000 Dijon<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mimouna Radi, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 3 80.56.64.23<br \/>\n<strong>Fax:<\/strong> (+33) 3 80.55.26.21<br \/>\n<strong>Email:<\/strong> cgrm.dijon@maec.gov.ma<br \/>\nconsulat-general-du-maroc@wanadoo.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-124508078\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado marroqu\u00ed en Dijon, Francia Direcci\u00f3n: 26, Rue Louis de Broglie B.P.79 21000 Dijon Francia Embajador: Mimouna Radi, C\u00f3nsul General Tel\u00e9fono: (+33) 3 80.56.64.23 Fax: (+33) 3 80.55.26.21 Email: cgrm.dijon@maec.gov.ma consulat-general-du-maroc@wanadoo.fr Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13368,14309,13000,13292],"tags":[12988],"class_list":["post-117273","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-marruecos","category-consulado-general-en-francia","category-francia","category-marruecos","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117273"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117273"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117273\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}