{"id":117156,"date":"2019-09-01T06:46:38","date_gmt":"2019-09-01T06:46:38","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-brasil-en-lyon-francia\/"},"modified":"2019-09-01T06:46:38","modified_gmt":"2019-09-01T06:46:38","slug":"consulado-de-brasil-en-lyon-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-brasil-en-lyon-francia\/","title":{"rendered":"Consulado de Brasil en Lyon, Francia"},"content":{"rendered":"<div id=\"trave-3836112392\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado brasile\u00f1o en Lyon, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n68 ter rue Chazi\u00e8re, o<br \/>\n2 Place de la Bourse<br \/>\n69004 Lyon<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Jean-Fran\u00e7ois Perrier, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 4 78.39.43.29<br \/>\n<strong>Fax:<\/strong> (+33) 4 78.39.43.29<br \/>\n<strong>Email:<\/strong> consulat.bresil.lyon@orange.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Con cita<\/p>\n<div id=\"trave-3141617946\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado brasile\u00f1o en Lyon, Francia Direcci\u00f3n: 68 ter rue Chazi\u00e8re, o 2 Place de la Bourse 69004 Lyon Francia Embajador: Jean-Fran\u00e7ois Perrier, C\u00f3nsul Honorario Tel\u00e9fono: (+33) 4 78.39.43.29 Fax: (+33) 4 78.39.43.29 Email: consulat.bresil.lyon@orange.fr Sitio web: Horas de oficina: Con cita<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13131,14310,13000],"tags":[12978],"class_list":["post-117156","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulados-de-brasil","category-consulados-en-francia","category-francia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117156"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117156"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117156\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}