{"id":117083,"date":"2019-09-01T06:45:59","date_gmt":"2019-09-01T06:45:59","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-santo-tome-y-principe-en-paris-francia\/"},"modified":"2019-09-01T06:45:59","modified_gmt":"2019-09-01T06:45:59","slug":"consulado-de-santo-tome-y-principe-en-paris-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-santo-tome-y-principe-en-paris-francia\/","title":{"rendered":"Consulado de Santo Tom\u00e9 y Pr\u00edncipe en Par\u00eds, Francia"},"content":{"rendered":"<div id=\"trave-3245260984\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Santo Tom\u00e9 en Par\u00eds, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n91200 Boulogne Billancourt<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 1 41 10 08 54<br \/>\n<strong>Fax:<\/strong> (+33) 1 41 10 03 19<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3395621216\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Santo Tom\u00e9 en Par\u00eds, Francia Direcci\u00f3n: 91200 Boulogne Billancourt Francia Embajador: Tel\u00e9fono: (+33) 1 41 10 08 54 Fax: (+33) 1 41 10 03 19 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13491,14310,13000,13490],"tags":[12978],"class_list":["post-117083","post","type-post","status-publish","format-standard","hentry","category-consulados-de-santo-tome","category-consulados-en-francia","category-francia","category-santo-tome-y-principe","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117083"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117083"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117083\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}