{"id":117056,"date":"2019-09-01T06:45:49","date_gmt":"2019-09-01T06:45:49","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-portugal-en-ajacio-francia\/"},"modified":"2019-09-01T06:45:49","modified_gmt":"2019-09-01T06:45:49","slug":"consulado-de-portugal-en-ajacio-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-portugal-en-ajacio-francia\/","title":{"rendered":"Consulado de Portugal en Ajacio, Francia"},"content":{"rendered":"<div id=\"trave-3076466518\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado portugu\u00e9s en Ajaccio, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n8 Place G\u00e9n\u00e9rale De Gaulle<br \/>\nResidencia le Diamant<br \/>\n20090 Ajaccio<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 495 50 37 34<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consulathonoraireportugal@orange.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1071624100\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado portugu\u00e9s en Ajaccio, Francia Direcci\u00f3n: 8 Place G\u00e9n\u00e9rale De Gaulle Residencia le Diamant 20090 Ajaccio Francia Embajador: Tel\u00e9fono: (+33) 495 50 37 34 Fax: Email: consulathonoraireportugal@orange.fr Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14310,13170,13000,6301],"tags":[12978],"class_list":["post-117056","post","type-post","status-publish","format-standard","hentry","category-consulados-en-francia","category-consulados-portugueses","category-francia","category-portugal","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117056"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117056"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117056\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}