{"id":116836,"date":"2019-09-01T06:43:47","date_gmt":"2019-09-01T06:43:47","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-austria-en-estrasburgo-francia\/"},"modified":"2019-09-01T06:43:47","modified_gmt":"2019-09-01T06:43:47","slug":"consulado-general-de-austria-en-estrasburgo-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-austria-en-estrasburgo-francia\/","title":{"rendered":"Consulado General de Austria en Estrasburgo, Francia"},"content":{"rendered":"<div id=\"trave-4220504435\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Austria en Estrasburgo, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n29, Avenue de la Paix<br \/>\n67000 Estrasburgo<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Erika Bernhard, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 388 35 13 94<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> strassburg-gk@bmeia.gv.at<br \/>\n<strong>Sitio web:<\/strong> www.bmeia.gv.at\/gk-strassburg\/<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 &#8211; 12.00<\/p>\n<div id=\"trave-3326019490\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Austria en Estrasburgo, Francia Direcci\u00f3n: 29, Avenue de la Paix 67000 Estrasburgo Francia Embajador: Erika Bernhard, C\u00f3nsul General Tel\u00e9fono: (+33) 388 35 13 94 Fax: Email: strassburg-gk@bmeia.gv.at Sitio web: www.bmeia.gv.at\/gk-strassburg\/ Horas de oficina: 09.00 &#8211; 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4857,13646,14309,13000],"tags":[12988],"class_list":["post-116836","post","type-post","status-publish","format-standard","hentry","category-austria","category-consulado-general-de-austria","category-consulado-general-en-francia","category-francia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/116836"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=116836"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/116836\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=116836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=116836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=116836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}