{"id":116781,"date":"2019-09-01T06:43:03","date_gmt":"2019-09-01T06:43:03","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-marruecos-en-paris-francia\/"},"modified":"2019-09-01T06:43:03","modified_gmt":"2019-09-01T06:43:03","slug":"consulado-general-de-marruecos-en-paris-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-marruecos-en-paris-francia\/","title":{"rendered":"Consulado General de Marruecos en Par\u00eds, Francia"},"content":{"rendered":"<div id=\"trave-3615356183\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado marroqu\u00ed en Par\u00eds, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n89 rue des Gros Gr\u00e8s<br \/>\n92700 Colombes<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Ali Semlali, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 1 56 83 80 20<br \/>\n<strong>Fax:<\/strong> (+33) 1 56 83 85 54<br \/>\n<strong>Email:<\/strong> cgmaroc.colombes@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 13.00<\/p>\n<div id=\"trave-3281124334\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado marroqu\u00ed en Par\u00eds, Francia Direcci\u00f3n: 89 rue des Gros Gr\u00e8s 92700 Colombes Francia Embajador: Mr Ali Semlali, C\u00f3nsul General Tel\u00e9fono: (+33) 1 56 83 80 20 Fax: (+33) 1 56 83 85 54 Email: cgmaroc.colombes@gmail.com Sitio web: Horas de oficina: 09.00 a 13.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13368,14309,13000,13292],"tags":[12988],"class_list":["post-116781","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-marruecos","category-consulado-general-en-francia","category-francia","category-marruecos","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/116781"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=116781"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/116781\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=116781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=116781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=116781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}