{"id":115931,"date":"2019-09-01T06:32:15","date_gmt":"2019-09-01T06:32:15","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-peru-en-machala-ecuador\/"},"modified":"2019-09-01T06:32:15","modified_gmt":"2019-09-01T06:32:15","slug":"consulado-general-de-peru-en-machala-ecuador","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-peru-en-machala-ecuador\/","title":{"rendered":"Consulado General de Per\u00fa en Machala, Ecuador"},"content":{"rendered":"<div id=\"trave-3756115099\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado peruano en Machala, Ecuador<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVilla 11 Providencia de El Oro<br \/>\nMachala<br \/>\nEcuador<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Don Alfonso Paz Sold\u00e1n, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 13.00 y 15.00 a 18.00<\/p>\n<div id=\"trave-3737216934\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado peruano en Machala, Ecuador Direcci\u00f3n: Villa 11 Providencia de El Oro Machala Ecuador Embajador: Don Alfonso Paz Sold\u00e1n, C\u00f3nsul General Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina: 09.00 a 13.00 y 15.00 a 18.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14243,13595,5314,6261],"tags":[12988],"class_list":["post-115931","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-ecuador","category-consulado-general-peruano","category-ecuador","category-peru","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115931"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115931"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115931\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}