{"id":115879,"date":"2019-09-01T06:31:48","date_gmt":"2019-09-01T06:31:48","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-mexico-en-quito-ecuador\/"},"modified":"2019-09-01T06:31:48","modified_gmt":"2019-09-01T06:31:48","slug":"embajada-de-mexico-en-quito-ecuador","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-mexico-en-quito-ecuador\/","title":{"rendered":"Embajada de M\u00e9xico en Quito, Ecuador"},"content":{"rendered":"<div id=\"trave-2548781453\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de M\u00e9xico en Quito, Ecuador<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSector el Batan<br \/>\nQuito<br \/>\nEcuador<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Jaime Manuel Del Arenal Fenochio, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+593) 244 8245<br \/>\n(+593) 2292 3771<br \/>\n<strong>Fax:<\/strong> (+593) 244 8245<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 14.00 y 15.30 a 18.00<\/p>\n<div id=\"trave-472288842\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de M\u00e9xico en Quito, Ecuador Direcci\u00f3n: Sector el Batan Quito Ecuador Embajador: Jaime Manuel Del Arenal Fenochio, Embajador Tel\u00e9fono: (+593) 244 8245 (+593) 2292 3771 Fax: (+593) 244 8245 Email: Sitio web: Horas de oficina: 09.00 a 14.00 y 15.30 a 18.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5314,14244,13356,5988],"tags":[12975],"class_list":["post-115879","post","type-post","status-publish","format-standard","hentry","category-ecuador","category-embajadas-en-ecuador","category-embajadas-mexicanas","category-mexico","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115879"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115879"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115879\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}