{"id":115842,"date":"2019-09-01T06:31:25","date_gmt":"2019-09-01T06:31:25","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-lituania-en-quito-ecuador\/"},"modified":"2019-09-01T06:31:25","modified_gmt":"2019-09-01T06:31:25","slug":"consulado-de-lituania-en-quito-ecuador","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-lituania-en-quito-ecuador\/","title":{"rendered":"Consulado de Lituania en Quito, Ecuador"},"content":{"rendered":"<div id=\"trave-188419413\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Lituania en Quito, Ecuador<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nReina Victoria N25-33 y Col\u00f3n<br \/>\nEdificio Banco de Guayaquil;Piso 7, Officina 705-A<br \/>\nQuito<br \/>\nEcuador<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dr. Raul Jaramillo-Andrade, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+593) 2 256 0824<br \/>\n(+593) 2 567 141 \/ 0997 100 555<br \/>\n<strong>Fax:<\/strong> (+593) 2 256 7141<br \/>\n<strong>Email:<\/strong> lietuvoskonsulatas@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 13.00 y 14.00 a 18.00<\/p>\n<div id=\"trave-3098476556\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Lituania en Quito, Ecuador Direcci\u00f3n: Reina Victoria N25-33 y Col\u00f3n Edificio Banco de Guayaquil;Piso 7, Officina 705-A Quito Ecuador Embajador: Dr. Raul Jaramillo-Andrade, C\u00f3nsul General Honorario Tel\u00e9fono: (+593) 2 256 0824 (+593) 2 567 141 \/ 0997 100 555 Fax: (+593) 2 256 7141 Email: lietuvoskonsulatas@gmail.com Sitio web: Horas de oficina: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13608,14242,5314,13184],"tags":[12978],"class_list":["post-115842","post","type-post","status-publish","format-standard","hentry","category-consulados-de-lituania","category-consulados-en-ecuador","category-ecuador","category-lituania","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115842"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115842"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115842\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}