{"id":115807,"date":"2019-09-01T06:30:50","date_gmt":"2019-09-01T06:30:50","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-espana-en-salinas-ecuador\/"},"modified":"2019-09-01T06:30:50","modified_gmt":"2019-09-01T06:30:50","slug":"consulado-de-espana-en-salinas-ecuador","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-espana-en-salinas-ecuador\/","title":{"rendered":"Consulado de Espa\u00f1a en Salinas, Ecuador"},"content":{"rendered":"<div id=\"trave-2054984335\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado espa\u00f1ol en Salinas, Ecuador<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAv.2a General Henr\u00edquez 609 y Calle 19-A<br \/>\nSalinas<br \/>\nEcuador<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Pedro Rizzo Pastor, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+593) (4) 277 2561<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> prizzo@andinave.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 12.30<\/p>\n<div id=\"trave-672170908\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado espa\u00f1ol en Salinas, Ecuador Direcci\u00f3n: Av.2a General Henr\u00edquez 609 y Calle 19-A Salinas Ecuador Embajador: Pedro Rizzo Pastor, C\u00f3nsul Honorario Tel\u00e9fono: (+593) (4) 277 2561 Fax: Email: prizzo@andinave.com Sitio web: Horas de oficina: 09.00 a 12.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14242,13537,5314,13134],"tags":[12978],"class_list":["post-115807","post","type-post","status-publish","format-standard","hentry","category-consulados-en-ecuador","category-consulados-espanoles","category-ecuador","category-espana","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115807"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115807"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115807\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}