{"id":115539,"date":"2019-09-01T06:27:28","date_gmt":"2019-09-01T06:27:28","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-suecia-en-esbjerg-dinamarca\/"},"modified":"2019-09-01T06:27:28","modified_gmt":"2019-09-01T06:27:28","slug":"consulado-de-suecia-en-esbjerg-dinamarca","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-suecia-en-esbjerg-dinamarca\/","title":{"rendered":"Consulado de Suecia en Esbjerg, Dinamarca"},"content":{"rendered":"<div id=\"trave-3815175456\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado sueco en Esbjerg, Dinamarca<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n6700 Esbjerg<br \/>\nDinamarca<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Klaus Kisum Kj\u00e6r, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+45) 88 91 90 01<br \/>\n<strong>Fax:<\/strong> (+45) 88 91 90 01<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2632477731\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado sueco en Esbjerg, Dinamarca Direcci\u00f3n: 6700 Esbjerg Dinamarca Embajador: Mr Klaus Kisum Kj\u00e6r, C\u00f3nsul Honorario Tel\u00e9fono: (+45) 88 91 90 01 Fax: (+45) 88 91 90 01 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14216,13528,13136,13073],"tags":[12978],"class_list":["post-115539","post","type-post","status-publish","format-standard","hentry","category-consulados-en-dinamarca","category-consulados-suecos","category-dinamarca","category-suecia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115539"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115539"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115539\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}