{"id":115403,"date":"2019-09-01T06:25:56","date_gmt":"2019-09-01T06:25:56","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-polonia-en-brno-republica-checa\/"},"modified":"2019-09-01T06:25:56","modified_gmt":"2019-09-01T06:25:56","slug":"consulado-de-polonia-en-brno-republica-checa","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-polonia-en-brno-republica-checa\/","title":{"rendered":"Consulado de Polonia en Brno, Rep\u00fablica Checa"},"content":{"rendered":"<div id=\"trave-2532100619\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado polaco en Brno, Rep\u00fablica Checa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nHudcova 367\/78<br \/>\n612 00 Brno<br \/>\nRep\u00fablica Checa<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+420) 775 412 957<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3013196892\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado polaco en Brno, Rep\u00fablica Checa Direcci\u00f3n: Hudcova 367\/78 612 00 Brno Rep\u00fablica Checa Embajador: Tel\u00e9fono: (+420) 775 412 957 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13477,14210,13263,13146],"tags":[12978],"class_list":["post-115403","post","type-post","status-publish","format-standard","hentry","category-consulados-de-polonia","category-consulados-en-republica-checa","category-polonia","category-republica-checa","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115403"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115403"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115403\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}