{"id":115396,"date":"2019-09-01T06:25:56","date_gmt":"2019-09-01T06:25:56","guid":{"rendered":"https:\/\/travelqa.com\/nunciatura-apostolica-de-la-santa-sede-en-praga-republica-checa\/"},"modified":"2019-09-01T06:25:56","modified_gmt":"2019-09-01T06:25:56","slug":"nunciatura-apostolica-de-la-santa-sede-en-praga-republica-checa","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/nunciatura-apostolica-de-la-santa-sede-en-praga-republica-checa\/","title":{"rendered":"Nunciatura Apost\u00f3lica de la Santa Sede en Praga, Rep\u00fablica Checa"},"content":{"rendered":"<div id=\"trave-1147644857\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Praga, Rep\u00fablica Checa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVor\u00c5ilska 121200<br \/>\n00 Praga 1<br \/>\nRep\u00fablica Checa<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Monsignore Giuseppe Leanza, Nuncio Apost\u00f3lico<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+420) 224 999 811<br \/>\n<strong>Fax:<\/strong> (+420) 224 999 833<br \/>\n<strong>Email:<\/strong> nunpraga@nunciatura.cz<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00 a 12.00<\/p>\n<div id=\"trave-3659873707\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Praga, Rep\u00fablica Checa Direcci\u00f3n: Vor\u00c5ilska 121200 00 Praga 1 Rep\u00fablica Checa Embajador: Monsignore Giuseppe Leanza, Nuncio Apost\u00f3lico Tel\u00e9fono: (+420) 224 999 811 Fax: (+420) 224 999 833 Email: nunpraga@nunciatura.cz Sitio web: Horas de oficina: 08.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14214,13146,13258,13260],"tags":[13262],"class_list":["post-115396","post","type-post","status-publish","format-standard","hentry","category-nunciatura-apostolica-en-la-republica-checa","category-republica-checa","category-santa-sede","category-santa-sede-nunciatura-apostolica","tag-nunciatura-apostolica"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115396"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115396"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115396\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}