{"id":115340,"date":"2019-09-01T06:25:24","date_gmt":"2019-09-01T06:25:24","guid":{"rendered":"https:\/\/travelqa.com\/oficina-de-representacion-de-taiwan-en-praga-republica-checa\/"},"modified":"2019-09-01T06:25:24","modified_gmt":"2019-09-01T06:25:24","slug":"oficina-de-representacion-de-taiwan-en-praga-republica-checa","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/oficina-de-representacion-de-taiwan-en-praga-republica-checa\/","title":{"rendered":"Oficina de representaci\u00f3n de Taiw\u00e1n en Praga, Rep\u00fablica Checa"},"content":{"rendered":"<div id=\"trave-190618430\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la oficina de representaci\u00f3n taiwanesa en Praga, Rep\u00fablica Checa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n160 00 Praga 6<br \/>\nRep\u00fablica Checa<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+420) 233 326 906<br \/>\n<strong>Fax:<\/strong> (+420) 233 326 906<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.30-11.30 y 13.30-16.30<\/p>\n<div id=\"trave-2967683128\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la oficina de representaci\u00f3n taiwanesa en Praga, Rep\u00fablica Checa Direcci\u00f3n: 160 00 Praga 6 Rep\u00fablica Checa Embajador: Tel\u00e9fono: (+420) 233 326 906 Fax: (+420) 233 326 906 Email: Sitio web: Horas de oficina: 09.30-11.30 y 13.30-16.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14213,13580,13146,6641],"tags":[12981],"class_list":["post-115340","post","type-post","status-publish","format-standard","hentry","category-oficinas-de-representacion-en-la-republica-checa","category-oficinas-representativas-de-taiwan","category-republica-checa","category-taiwan","tag-oficina-representativa"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115340"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=115340"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/115340\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=115340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=115340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=115340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}