{"id":114796,"date":"2019-09-01T06:18:47","date_gmt":"2019-09-01T06:18:47","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-pakistan-en-san-jose-costa-rica\/"},"modified":"2019-09-01T06:18:47","modified_gmt":"2019-09-01T06:18:47","slug":"consulado-de-pakistan-en-san-jose-costa-rica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-pakistan-en-san-jose-costa-rica\/","title":{"rendered":"Consulado de Pakist\u00e1n en San Jos\u00e9, Costa Rica"},"content":{"rendered":"<div id=\"trave-3483821038\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado paquistan\u00ed en San Jos\u00e9, Costa Rica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBarrio Tourn\u00f3n<br \/>\nOficentro Torres del Campo, Edificio 1, piso dos<br \/>\nBufete Aguilar y Asociados<br \/>\nSan Jos\u00e9 \u00a9<br \/>\nCosta Rica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Luis Alberto Varela Quir\u00f3s, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+506) 2221-0275<br \/>\n<strong>Fax:<\/strong> (+506) 2233-4898<br \/>\n<strong>Email:<\/strong> consulpakistancr@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00 a 12.00 y 15.00 a 17.00<\/p>\n<div id=\"trave-3460330425\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado paquistan\u00ed en San Jos\u00e9, Costa Rica Direcci\u00f3n: Barrio Tourn\u00f3n Oficentro Torres del Campo, Edificio 1, piso dos Bufete Aguilar y Asociados San Jos\u00e9 \u00a9 Costa Rica Embajador: Luis Alberto Varela Quir\u00f3s, C\u00f3nsul Honorario Tel\u00e9fono: (+506) 2221-0275 Fax: (+506) 2233-4898 Email: consulpakistancr@gmail.com Sitio web: Horas de oficina: 10.00 a 12.00 y 15.00 a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13243,14171,5199,6205],"tags":[12978],"class_list":["post-114796","post","type-post","status-publish","format-standard","hentry","category-consulados-de-pakistan","category-consulados-en-costa-rica","category-costa-rica","category-pakistan","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114796"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114796"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114796\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}