{"id":114756,"date":"2019-09-01T06:18:21","date_gmt":"2019-09-01T06:18:21","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-honduras-en-san-jose-costa-rica\/"},"modified":"2019-09-01T06:18:21","modified_gmt":"2019-09-01T06:18:21","slug":"embajada-de-honduras-en-san-jose-costa-rica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-honduras-en-san-jose-costa-rica\/","title":{"rendered":"Embajada de Honduras en San Jos\u00e9, Costa Rica"},"content":{"rendered":"<div id=\"trave-983434916\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Honduras en San Jos\u00e9, Costa Rica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nEsquina al norestedel Canal 7 de Teletica a<br \/>\n175<br \/>\nmetros de distancia, con un servicio de transporte a las azores<br \/>\nApartado Postal 2239, Rohrmoser<br \/>\n1000 San Jos\u00e9<br \/>\nCosta Rica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Juan Alberto Lara Bueso, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+506) 2232 9506<br \/>\n<strong>Fax:<\/strong> (+506) 2291 5147<br \/>\n<strong>Email:<\/strong> embhoncr@embajadahonduras.co.cr<br \/>\nconsulado@embajadahonduras.co.cr<br \/>\n<strong>Sitio web:<\/strong> www.embajadahonduras.co.cr<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00-17.00<\/p>\n<div id=\"trave-3080453835\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Honduras en San Jos\u00e9, Costa Rica Direcci\u00f3n: Esquina al norestedel Canal 7 de Teletica a 175 metros de distancia, con un servicio de transporte a las azores Apartado Postal 2239, Rohrmoser 1000 San Jos\u00e9 Costa Rica Embajador: Sr. Juan Alberto Lara Bueso, Embajador Tel\u00e9fono: (+506) 2232 9506 Fax: (+506) 2291 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5199,14172,13549,5584],"tags":[12975],"class_list":["post-114756","post","type-post","status-publish","format-standard","hentry","category-costa-rica","category-embajadas-en-costa-rica","category-embajadas-hondurenas","category-honduras","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114756"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114756"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114756\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}