{"id":114725,"date":"2019-09-01T06:17:28","date_gmt":"2019-09-01T06:17:28","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-ghana-en-brazzaville-congo-republica-de\/"},"modified":"2019-09-01T06:17:28","modified_gmt":"2019-09-01T06:17:28","slug":"consulado-general-de-ghana-en-brazzaville-congo-republica-de","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-ghana-en-brazzaville-congo-republica-de\/","title":{"rendered":"Consulado General de Ghana en Brazzaville, Congo, Rep\u00fablica de"},"content":{"rendered":"<div id=\"trave-1710576577\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Ghana en Brazzaville, Congo, Rep\u00fablica de<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1 Parcelle du Lyc\u00e9e Chaminade<br \/>\nAvenue Des Prerses<br \/>\nBP 15015<br \/>\nBrazzaville<br \/>\nCongo (Rep\u00fablica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Daniel Kingsley Atta Boafo, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+242) 06 580 4747 \/ 05 357 5522<br \/>\n(+242) 05 559 0016 (Consular section)<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> ghanaconsulatebzv@gmail.com<br \/>\nghconsbrazza@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-15.00<\/p>\n<div id=\"trave-3122760957\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Ghana en Brazzaville, Congo, Rep\u00fablica de Direcci\u00f3n: 1 Parcelle du Lyc\u00e9e Chaminade Avenue Des Prerses BP 15015 Brazzaville Congo (Rep\u00fablica) Embajador: Daniel Kingsley Atta Boafo, C\u00f3nsul General Tel\u00e9fono: (+242) 06 580 4747 \/ 05 357 5522 (+242) 05 559 0016 (Consular section) Fax: Email: ghanaconsulatebzv@gmail.com ghconsbrazza@gmail.com Sitio web: Horas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14019,14162,5482,13362],"tags":[12988],"class_list":["post-114725","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-ghana","category-consulado-general-en-republica-del-congo-de","category-ghana","category-republica-del-congo-de","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114725"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114725"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114725\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}