{"id":114715,"date":"2019-09-01T06:17:23","date_gmt":"2019-09-01T06:17:23","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-espana-en-brazzaville-congo-republica-de\/"},"modified":"2019-09-01T06:17:23","modified_gmt":"2019-09-01T06:17:23","slug":"consulado-de-espana-en-brazzaville-congo-republica-de","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-espana-en-brazzaville-congo-republica-de\/","title":{"rendered":"Consulado de Espa\u00f1a en Brazzaville, Congo, Rep\u00fablica de"},"content":{"rendered":"<div id=\"trave-1258678142\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado espa\u00f1ol en Brazzaville, Congo, Rep\u00fablica de<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n15 Rue Duplex<br \/>\ncara a cara Madame Adada de propiedad privada CCF<br \/>\nBrazzaville<br \/>\nCongo (Rep\u00fablica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Bangana Betou, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+242) 050 939 177<br \/>\n(+242) 068 112 767<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-43936267\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado espa\u00f1ol en Brazzaville, Congo, Rep\u00fablica de Direcci\u00f3n: 15 Rue Duplex cara a cara Madame Adada de propiedad privada CCF Brazzaville Congo (Rep\u00fablica) Embajador: Bangana Betou, C\u00f3nsul Honorario Tel\u00e9fono: (+242) 050 939 177 (+242) 068 112 767 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14160,13537,13134,13362],"tags":[12978],"class_list":["post-114715","post","type-post","status-publish","format-standard","hentry","category-consulados-en-republica-del-congo","category-consulados-espanoles","category-espana","category-republica-del-congo-de","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114715"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114715"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114715\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}