{"id":114694,"date":"2019-09-01T06:17:10","date_gmt":"2019-09-01T06:17:10","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-suecia-en-brazzaville-congo-republica-de\/"},"modified":"2019-09-01T06:17:10","modified_gmt":"2019-09-01T06:17:10","slug":"consulado-de-suecia-en-brazzaville-congo-republica-de","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-suecia-en-brazzaville-congo-republica-de\/","title":{"rendered":"Consulado de Suecia en Brazzaville, Congo, Rep\u00fablica de"},"content":{"rendered":"<div id=\"trave-390693988\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado sueco en Brazzaville, Congo, Rep\u00fablica de<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n3, rue P\u00e8re Bessieux<br \/>\nCentre-ville<br \/>\nB.P.13945<br \/>\nBrazzaville<br \/>\nCongo (Rep\u00fablica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dominique Picard, C\u00f3nsul<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+242) 066 647 323<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4086754291\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado sueco en Brazzaville, Congo, Rep\u00fablica de Direcci\u00f3n: 3, rue P\u00e8re Bessieux Centre-ville B.P.13945 Brazzaville Congo (Rep\u00fablica) Embajador: Dominique Picard, C\u00f3nsul Tel\u00e9fono: (+242) 066 647 323 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14160,13528,13362,13073],"tags":[12978],"class_list":["post-114694","post","type-post","status-publish","format-standard","hentry","category-consulados-en-republica-del-congo","category-consulados-suecos","category-republica-del-congo-de","category-suecia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114694"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114694"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114694\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}