{"id":114636,"date":"2019-09-01T06:16:27","date_gmt":"2019-09-01T06:16:27","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-israel-en-kinshasa-congo-republica-democratica-del\/"},"modified":"2019-09-01T06:16:27","modified_gmt":"2019-09-01T06:16:27","slug":"consulado-de-israel-en-kinshasa-congo-republica-democratica-del","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-israel-en-kinshasa-congo-republica-democratica-del\/","title":{"rendered":"Consulado de Israel en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del"},"content":{"rendered":"<div id=\"trave-3258674263\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado israel\u00ed en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nKinshasa<br \/>\nCongo (Rep\u00fablica Democr\u00e1tica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Aslan Piha, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1590798725\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado israel\u00ed en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del Direcci\u00f3n: Kinshasa Congo (Rep\u00fablica Democr\u00e1tica) Embajador: Aslan Piha, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13253,14156,5685,13342],"tags":[12978],"class_list":["post-114636","post","type-post","status-publish","format-standard","hentry","category-consulados-de-israel","category-consulados-en-republica-democratica-del-congo-de","category-israel","category-republica-democratica-del-congo","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114636"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114636"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114636\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}