{"id":114604,"date":"2019-09-01T06:15:57","date_gmt":"2019-09-01T06:15:57","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-sudafrica-en-kinshasa-congo-republica-democratica-del\/"},"modified":"2019-09-01T06:15:57","modified_gmt":"2019-09-01T06:15:57","slug":"embajada-de-sudafrica-en-kinshasa-congo-republica-democratica-del","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-sudafrica-en-kinshasa-congo-republica-democratica-del\/","title":{"rendered":"Embajada de Sud\u00e1frica en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del"},"content":{"rendered":"<div id=\"trave-176337450\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Sud\u00e1frica en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n77 Avenue Ngongo Lutete<br \/>\nGombe<br \/>\nBoite Postale 7829<br \/>\nKinshasa 1<br \/>\nCongo (Rep\u00fablica Democr\u00e1tica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. N. Mashimbye, embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+243) 81 556 6586<br \/>\n<strong>Fax:<\/strong> (+243) 81 555 4321<br \/>\n<strong>Email:<\/strong> ambasud@stelecom.cd<br \/>\nmahapae@dirco.gov.za<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2975338651\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Sud\u00e1frica en Kinshasa, Congo, Rep\u00fablica Democr\u00e1tica del Direcci\u00f3n: 77 Avenue Ngongo Lutete Gombe Boite Postale 7829 Kinshasa 1 Congo (Rep\u00fablica Democr\u00e1tica) Embajador: Sr. N. Mashimbye, embajador Tel\u00e9fono: (+243) 81 556 6586 Fax: (+243) 81 555 4321 Email: ambasud@stelecom.cd mahapae@dirco.gov.za Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14154,13326,13342,13251],"tags":[12975],"class_list":["post-114604","post","type-post","status-publish","format-standard","hentry","category-embajadas-en-republica-democratica-del-congo-de","category-embajadas-sudafricanas","category-republica-democratica-del-congo","category-sudafrica","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114604"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114604"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114604\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}