{"id":114119,"date":"2019-09-01T06:10:27","date_gmt":"2019-09-01T06:10:27","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-belgica-en-guangzhou-china\/"},"modified":"2019-09-01T06:10:27","modified_gmt":"2019-09-01T06:10:27","slug":"consulado-general-de-belgica-en-guangzhou-china","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-belgica-en-guangzhou-china\/","title":{"rendered":"Consulado General de B\u00e9lgica en Guangzhou, China"},"content":{"rendered":"<div id=\"trave-2734279243\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado belga en Guangzhou, China<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n10 Huaxia Lu &#8211;<br \/>\nDistritoZhujiang Xin ChengTianhe<br \/>\n510623 Guangzhou<br \/>\nChina<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Christian de Lannoy, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1471020483\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado belga en Guangzhou, China Direcci\u00f3n: 10 Huaxia Lu &#8211; DistritoZhujiang Xin ChengTianhe 510623 Guangzhou China Embajador: Christian de Lannoy, C\u00f3nsul General Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,5145,14003,14121],"tags":[12988],"class_list":["post-114119","post","type-post","status-publish","format-standard","hentry","category-belgica","category-china","category-consulado-general-belga","category-consulado-general-en-china","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114119"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114119"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114119\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}