{"id":114024,"date":"2019-09-01T06:09:24","date_gmt":"2019-09-01T06:09:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-mongolia-en-hailar-china\/"},"modified":"2019-09-01T06:09:24","modified_gmt":"2019-09-01T06:09:24","slug":"consulado-de-mongolia-en-hailar-china","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-mongolia-en-hailar-china\/","title":{"rendered":"Consulado de Mongolia en Hailar, China"},"content":{"rendered":"<div id=\"trave-3752955479\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Mongolia en Hailar, China<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n5 Baihuaxilu Street<br \/>\nHailar<br \/>\nChina<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Damba Ganbold, C\u00f3nsul<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+86) 470-811 2897<br \/>\n<strong>Fax:<\/strong> (+86) 470-811 2895<br \/>\n<strong>Email:<\/strong> hailaar@mfa.gov.mn<br \/>\n<strong>Sitio web:<\/strong> hailar.consul.mn\/eng\/<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3162305638\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Mongolia en Hailar, China Direcci\u00f3n: 5 Baihuaxilu Street Hailar China Embajador: Mr Damba Ganbold, C\u00f3nsul Tel\u00e9fono: (+86) 470-811 2897 Fax: (+86) 470-811 2895 Email: hailaar@mfa.gov.mn Sitio web: hailar.consul.mn\/eng\/ Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5145,13270,14122,6025],"tags":[12978],"class_list":["post-114024","post","type-post","status-publish","format-standard","hentry","category-china","category-consulados-de-mongolia","category-consulados-en-china","category-mongolia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114024"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=114024"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/114024\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=114024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=114024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=114024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}