{"id":113731,"date":"2019-09-01T06:05:55","date_gmt":"2019-09-01T06:05:55","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-senegal-en-bangui-republica-centroafricana\/"},"modified":"2019-09-01T06:05:55","modified_gmt":"2019-09-01T06:05:55","slug":"consulado-de-senegal-en-bangui-republica-centroafricana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-senegal-en-bangui-republica-centroafricana\/","title":{"rendered":"Consulado de Senegal en Bangui, Rep\u00fablica Centroafricana"},"content":{"rendered":"<div id=\"trave-3865608094\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado senegal\u00e9s en Bangui, Rep\u00fablica Centroafricana<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBP 1024<br \/>\nBangui<br \/>\nRep\u00fablica Centroafricana<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Adama Gueye, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+236) 2161 2770<br \/>\n<strong>Fax:<\/strong> (+236) 2161 7359<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1239501026\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado senegal\u00e9s en Bangui, Rep\u00fablica Centroafricana Direcci\u00f3n: BP 1024 Bangui Rep\u00fablica Centroafricana Embajador: Adama Gueye, C\u00f3nsul Honorario Tel\u00e9fono: (+236) 2161 2770 Fax: (+236) 2161 7359 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14105,13799,13870,6440],"tags":[12978],"class_list":["post-113731","post","type-post","status-publish","format-standard","hentry","category-consulados-en-republica-centroafricana","category-consulados-senegaleses","category-republica-centroafricana","category-senegal","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113731"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=113731"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113731\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=113731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=113731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=113731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}