{"id":113633,"date":"2019-09-01T06:04:27","date_gmt":"2019-09-01T06:04:27","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-mali-en-quebec-canada\/"},"modified":"2019-09-01T06:04:27","modified_gmt":"2019-09-01T06:04:27","slug":"consulado-general-de-mali-en-quebec-canada","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-mali-en-quebec-canada\/","title":{"rendered":"Consulado General de Mal\u00ed en Quebec, Canad\u00e1"},"content":{"rendered":"<div id=\"trave-3719137575\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Mali en Quebec, Canad\u00e1<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n14 Jardins de Madrid, Suite 1009<br \/>\nQu\u00e9bec, QC G1S 4Z6<br \/>\nCanad\u00e1<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sra. Suzie Harvey, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) (418) 569-5237<br \/>\n<strong>Fax:<\/strong> (+1) (418) 644-6851<br \/>\n<strong>Email:<\/strong> consuledumali.quebec@videotron.ca<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3952765842\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Mali en Quebec, Canad\u00e1 Direcci\u00f3n: 14 Jardins de Madrid, Suite 1009 Qu\u00e9bec, QC G1S 4Z6 Canad\u00e1 Embajador: Sra. Suzie Harvey, C\u00f3nsul General Honorario Tel\u00e9fono: (+1) (418) 569-5237 Fax: (+1) (418) 644-6851 Email: consuledumali.quebec@videotron.ca Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5085,13460,14065,5941],"tags":[12988],"class_list":["post-113633","post","type-post","status-publish","format-standard","hentry","category-canada","category-consulado-general-de-mali","category-consulado-general-en-canada","category-mali","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113633"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=113633"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113633\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=113633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=113633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=113633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}