{"id":113545,"date":"2019-09-01T06:03:40","date_gmt":"2019-09-01T06:03:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-peru-en-montreal-canada\/"},"modified":"2019-09-01T06:03:40","modified_gmt":"2019-09-01T06:03:40","slug":"consulado-general-de-peru-en-montreal-canada","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-peru-en-montreal-canada\/","title":{"rendered":"Consulado General de Per\u00fa en Montreal, Canad\u00e1"},"content":{"rendered":"<div id=\"trave-3904590255\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado peruano en Montreal, Canad\u00e1<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n550 Sherbrooke Street West, Suite 970, West Tower<br \/>\nMontr\u00e9al, QC H3A 1B9<br \/>\nCanad\u00e1<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Manuel de Coss\u00c3o Kl\u00fcver, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 514 844 5123<br \/>\n<strong>Fax:<\/strong> (+1) 514 843 8425<br \/>\n<strong>Email:<\/strong> portalwebmontreal@rree.gob.pe<br \/>\n<strong>Sitio web:<\/strong> www.consulado.pe\/es\/montreal<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1051746092\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado peruano en Montreal, Canad\u00e1 Direcci\u00f3n: 550 Sherbrooke Street West, Suite 970, West Tower Montr\u00e9al, QC H3A 1B9 Canad\u00e1 Embajador: Manuel de Coss\u00c3o Kl\u00fcver, C\u00f3nsul General Tel\u00e9fono: (+1) 514 844 5123 Fax: (+1) 514 843 8425 Email: portalwebmontreal@rree.gob.pe Sitio web: www.consulado.pe\/es\/montreal Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5085,14065,13595,6261],"tags":[12988],"class_list":["post-113545","post","type-post","status-publish","format-standard","hentry","category-canada","category-consulado-general-en-canada","category-consulado-general-peruano","category-peru","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113545"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=113545"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113545\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=113545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=113545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=113545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}