{"id":113528,"date":"2019-09-01T06:03:20","date_gmt":"2019-09-01T06:03:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-noruega-en-toronto-canada\/"},"modified":"2019-09-01T06:03:20","modified_gmt":"2019-09-01T06:03:20","slug":"consulado-general-de-noruega-en-toronto-canada","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-noruega-en-toronto-canada\/","title":{"rendered":"Consulado General de Noruega en Toronto, Canad\u00e1"},"content":{"rendered":"<div id=\"trave-3700443885\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Noruega en Toronto, Canad\u00e1<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n2 Bloor Street West, Suite 2109<br \/>\nToronto, ON M4W 3E2<br \/>\nCanad\u00e1<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sra. Marianne Koritzinsky, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 416 920 5287<br \/>\n<strong>Fax:<\/strong> (+1) 416 920 0536<br \/>\n<strong>Email:<\/strong> norwegianconsulategeneral.to@gmail.com<br \/>\n<strong>Sitio web:<\/strong> www.norway.no\/en\/canada<\/p>\n<p><strong>Horas de oficina:<\/strong> Solo por cita<\/p>\n<div id=\"trave-1132678174\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Noruega en Toronto, Canad\u00e1 Direcci\u00f3n: 2 Bloor Street West, Suite 2109 Toronto, ON M4W 3E2 Canad\u00e1 Embajador: Sra. Marianne Koritzinsky, C\u00f3nsul General Honorario Tel\u00e9fono: (+1) 416 920 5287 Fax: (+1) 416 920 0536 Email: norwegianconsulategeneral.to@gmail.com Sitio web: www.norway.no\/en\/canada Horas de oficina: Solo por cita<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5085,13261,14065,13153],"tags":[12988],"class_list":["post-113528","post","type-post","status-publish","format-standard","hentry","category-canada","category-consulado-general-de-noruega","category-consulado-general-en-canada","category-noruega","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113528"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=113528"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113528\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=113528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=113528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=113528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}