{"id":113153,"date":"2019-09-01T05:59:08","date_gmt":"2019-09-01T05:59:08","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-finlandia-en-edmonton-canada\/"},"modified":"2019-09-01T05:59:08","modified_gmt":"2019-09-01T05:59:08","slug":"consulado-de-finlandia-en-edmonton-canada","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-finlandia-en-edmonton-canada\/","title":{"rendered":"Consulado de Finlandia en Edmonton, Canad\u00e1"},"content":{"rendered":"<div id=\"trave-2015747126\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado finland\u00e9s en Edmonton, Canad\u00e1<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1400 Canadian Western Bank Place<br \/>\n10303 Jasper Avenue<br \/>\nEdmonton, AB T5J 3N6<br \/>\nCanad\u00e1<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Theodore D. Boss\u00e9, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1) 780 421 1818<br \/>\n<strong>Fax:<\/strong> (+1) 780 429 4453<br \/>\n<strong>Email:<\/strong> tbosse@ogilvielaw.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1573522072\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado finland\u00e9s en Edmonton, Canad\u00e1 Direcci\u00f3n: 1400 Canadian Western Bank Place 10303 Jasper Avenue Edmonton, AB T5J 3N6 Canad\u00e1 Embajador: Mr Theodore D. Boss\u00e9, C\u00f3nsul Honorario Tel\u00e9fono: (+1) 780 421 1818 Fax: (+1) 780 429 4453 Email: tbosse@ogilvielaw.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5085,14064,13285,12998],"tags":[12978],"class_list":["post-113153","post","type-post","status-publish","format-standard","hentry","category-canada","category-consulados-en-canada","category-consulados-finlandeses","category-finlandia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113153"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=113153"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/113153\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=113153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=113153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=113153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}