{"id":112723,"date":"2019-09-01T05:51:29","date_gmt":"2019-09-01T05:51:29","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-timor-oriental-en-bandar-seri-begawan-brunei\/"},"modified":"2019-09-01T05:51:29","modified_gmt":"2019-09-01T05:51:29","slug":"embajada-de-timor-oriental-en-bandar-seri-begawan-brunei","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-timor-oriental-en-bandar-seri-begawan-brunei\/","title":{"rendered":"Embajada de Timor Oriental en Bandar Seri Begawan, Brunei"},"content":{"rendered":"<div id=\"trave-1821428513\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Timor-Leste en Bandar Seri Begawan, Brunei<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nKampong Salambigar BC1515<br \/>\nBandar Seri Begawan<br \/>\nBrunei<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Eminio da Silva Pinto, Encargado de Negocios ai<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+673) 233 99224<br \/>\n<strong>Fax:<\/strong> (+673) 233 99224<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30 a 12.30 y 13.30 a 16.30<\/p>\n<div id=\"trave-2277102327\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Timor-Leste en Bandar Seri Begawan, Brunei Direcci\u00f3n: Kampong Salambigar BC1515 Bandar Seri Begawan Brunei Embajador: Sr. Eminio da Silva Pinto, Encargado de Negocios ai Tel\u00e9fono: (+673) 233 99224 Fax: (+673) 233 99224 Email: Sitio web: Horas de oficina: 08.30 a 12.30 y 13.30 a 16.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5025,13506,14027,6684],"tags":[12975],"class_list":["post-112723","post","type-post","status-publish","format-standard","hentry","category-brunei","category-embajadas-de-timor-leste","category-embajadas-en-brunei","category-timor-leste","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112723"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112723"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112723\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}