{"id":112626,"date":"2019-09-01T05:48:21","date_gmt":"2019-09-01T05:48:21","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-guinea-en-rio-de-janeiro-brasil\/"},"modified":"2019-09-01T05:48:21","modified_gmt":"2019-09-01T05:48:21","slug":"consulado-general-de-guinea-en-rio-de-janeiro-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-guinea-en-rio-de-janeiro-brasil\/","title":{"rendered":"Consulado General de Guinea en R\u00edo de Janeiro, Brasil"},"content":{"rendered":"<div id=\"trave-2869899814\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Guinea en R\u00edo de Janeiro, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAv.Franklin Roosevelt, 194, Grupo 702<br \/>\nCentro<br \/>\n20021-120 R\u00edo de Janeiro &#8211; RJ<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Fod\u00e9 Tour\u00e9, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 21 2220 7545<br \/>\n<strong>Fax:<\/strong> (+55) 21 2220 6781<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2060905507\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Guinea en R\u00edo de Janeiro, Brasil Direcci\u00f3n: Av.Franklin Roosevelt, 194, Grupo 702 Centro 20021-120 R\u00edo de Janeiro &#8211; RJ Brasil Embajador: Mr Fod\u00e9 Tour\u00e9, C\u00f3nsul General Honorario Tel\u00e9fono: (+55) 21 2220 7545 Fax: (+55) 21 2220 6781 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,14020,13998,5542],"tags":[12988],"class_list":["post-112626","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulado-general-de-guinea","category-consulado-general-en-brasil","category-guinea","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112626"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112626"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112626\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}