{"id":112616,"date":"2019-09-01T05:47:38","date_gmt":"2019-09-01T05:47:38","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-la-republica-de-corea-en-manaos-brasil\/"},"modified":"2019-09-01T05:47:38","modified_gmt":"2019-09-01T05:47:38","slug":"consulado-general-de-la-republica-de-corea-en-manaos-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-la-republica-de-corea-en-manaos-brasil\/","title":{"rendered":"Consulado General de la Rep\u00fablica de Corea en Manaos, Brasil"},"content":{"rendered":"<div id=\"trave-3937145859\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Corea del Sur en Manaos, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua 01,215 &#8211; Bairro da Paz<br \/>\nManaus &#8211; AM<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Jos\u00e9 Raphael Siqueira Filho, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> jrsiqueirafilho@uol.com.br<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1734174280\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Corea del Sur en Manaos, Brasil Direcci\u00f3n: Rua 01,215 &#8211; Bairro da Paz Manaus &#8211; AM Brasil Embajador: Mr Jos\u00e9 Raphael Siqueira Filho, C\u00f3nsul General Honorario Tel\u00e9fono: Fax: Email: jrsiqueirafilho@uol.com.br Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13619,13998,13151],"tags":[12988],"class_list":["post-112616","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulado-general-de-corea-del-sur","category-consulado-general-en-brasil","category-corea-del-sur-republica-de","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112616"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112616"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112616\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}