{"id":112423,"date":"2019-09-01T05:46:17","date_gmt":"2019-09-01T05:46:17","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-paraguay-en-sao-paulo-brasil\/"},"modified":"2019-09-01T05:46:17","modified_gmt":"2019-09-01T05:46:17","slug":"consulado-general-de-paraguay-en-sao-paulo-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-paraguay-en-sao-paulo-brasil\/","title":{"rendered":"Consulado General de Paraguay en Sao Paulo, Brasil"},"content":{"rendered":"<div id=\"trave-945345680\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado paraguayo en Sao Paulo, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua Bandeira Paulista, 600<br \/>\nConjuntos 81\/82 &#8211; 8 \u00b0 \u00b0<br \/>\nEdifio Acyr Andrade<br \/>\nBairro Itaim<br \/>\n04532-001 S\u00e3o Paulo &#8211; SP<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Oscar Rodolfo Ben\u00edtez Estrag\u00f3, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 11 3167 0455<br \/>\n<strong>Fax:<\/strong> (+55) 11 3167 0412<br \/>\n<strong>Email:<\/strong> sanpablocongralpar@mre.gov.py<br \/>\nconsulpyso@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-937038950\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado paraguayo en Sao Paulo, Brasil Direcci\u00f3n: Rua Bandeira Paulista, 600 Conjuntos 81\/82 &#8211; 8 \u00b0 \u00b0 Edifio Acyr Andrade Bairro Itaim 04532-001 S\u00e3o Paulo &#8211; SP Brasil Embajador: Oscar Rodolfo Ben\u00edtez Estrag\u00f3, C\u00f3nsul General Tel\u00e9fono: (+55) 11 3167 0455 Fax: (+55) 11 3167 0412 Email: sanpablocongralpar@mre.gov.py consulpyso@gmail.com Sitio web: Horas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13998,13971,6252],"tags":[12988],"class_list":["post-112423","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulado-general-en-brasil","category-consulado-general-paraguayo","category-paraguay","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112423"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112423"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112423\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}