{"id":112417,"date":"2019-09-01T05:46:10","date_gmt":"2019-09-01T05:46:10","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-paraguay-en-foz-de-iguazu-brasil\/"},"modified":"2019-09-01T05:46:10","modified_gmt":"2019-09-01T05:46:10","slug":"consulado-general-de-paraguay-en-foz-de-iguazu-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-paraguay-en-foz-de-iguazu-brasil\/","title":{"rendered":"Consulado General de Paraguay en Foz de Iguaz\u00fa, Brasil"},"content":{"rendered":"<div id=\"trave-2805758534\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado paraguayo en Foz de Iguaz\u00fa, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua Marechal Deodoro en 901<br \/>\nCentro<br \/>\n85851-030 Foz do Igua\u00e7u &#8211; PR<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Juan Alberto Baiardi Quesnel, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 45 3523-2898<br \/>\n(+55) 45 3523 9212<br \/>\n<strong>Fax:<\/strong> (+55) 45 3523-2898<br \/>\n(+55) 45 3523 9212<br \/>\n<strong>Email:<\/strong> fozconsulpar@mre.gov.py<br \/>\nconsuladodelparaguayfoz@hotmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30 a 12.30 y 13.30 a 15.30<\/p>\n<div id=\"trave-3434433054\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado paraguayo en Foz de Iguaz\u00fa, Brasil Direcci\u00f3n: Rua Marechal Deodoro en 901 Centro 85851-030 Foz do Igua\u00e7u &#8211; PR Brasil Embajador: Juan Alberto Baiardi Quesnel, C\u00f3nsul General Tel\u00e9fono: (+55) 45 3523-2898 (+55) 45 3523 9212 Fax: (+55) 45 3523-2898 (+55) 45 3523 9212 Email: fozconsulpar@mre.gov.py consuladodelparaguayfoz@hotmail.com Sitio web: Horas de oficina: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13998,13971,6252],"tags":[12988],"class_list":["post-112417","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulado-general-en-brasil","category-consulado-general-paraguayo","category-paraguay","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112417"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112417"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112417\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}