{"id":112252,"date":"2019-09-01T05:27:23","date_gmt":"2019-09-01T05:27:23","guid":{"rendered":"https:\/\/travelqa.com\/agencia-consular-de-italia-en-santa-maria-brasil\/"},"modified":"2019-09-01T05:27:23","modified_gmt":"2019-09-01T05:27:23","slug":"agencia-consular-de-italia-en-santa-maria-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/agencia-consular-de-italia-en-santa-maria-brasil\/","title":{"rendered":"Agencia Consular de Italia en Santa Maria, Brasil"},"content":{"rendered":"<div id=\"trave-2463615850\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Agencia Consular Italiana en Santa Maria, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAv.Nossa Senhora das Dores, 2270<br \/>\n97050-530 &#8211; Santa Maria \/ RS<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Oscar Jos\u00e9 Carlesso, Agente Consular<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 55 3028 3060<br \/>\n<strong>Fax:<\/strong> (+55) 55 3028 3060<br \/>\n<strong>Email:<\/strong> santamaria.onorario@esteri.it<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-557362710\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Agencia Consular Italiana en Santa Maria, Brasil Direcci\u00f3n: Av.Nossa Senhora das Dores, 2270 97050-530 &#8211; Santa Maria \/ RS Brasil Embajador: Oscar Jos\u00e9 Carlesso, Agente Consular Tel\u00e9fono: (+55) 55 3028 3060 Fax: (+55) 55 3028 3060 Email: santamaria.onorario@esteri.it Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14007,13577,13130,13062],"tags":[13532],"class_list":["post-112252","post","type-post","status-publish","format-standard","hentry","category-agencias-consulares-en-brasil","category-agencias-consulares-italianas","category-brasil","category-italia","tag-agencia-consular"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112252"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112252"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112252\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}