{"id":112225,"date":"2019-09-01T05:27:08","date_gmt":"2019-09-01T05:27:08","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-italia-en-recife-brasil\/"},"modified":"2019-09-01T05:27:08","modified_gmt":"2019-09-01T05:27:08","slug":"consulado-de-italia-en-recife-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-italia-en-recife-brasil\/","title":{"rendered":"Consulado de Italia en Recife, Brasil"},"content":{"rendered":"<div id=\"trave-1523503637\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado italiano en Recife, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nrua Padre Carapuceiro 706 &#8211; 13 \u00b0<br \/>\nBairro Boa Viagem<br \/>\n51010-030 Recife &#8211; PE<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Gabor de Zagon, C\u00f3nsul<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 81 3035 4700<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consolato.recife@esteri.it<br \/>\n<strong>Sitio web:<\/strong> consrecife.esteri.it\/consolato_recife\/it\/<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-248818503\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado italiano en Recife, Brasil Direcci\u00f3n: rua Padre Carapuceiro 706 &#8211; 13 \u00b0 Bairro Boa Viagem 51010-030 Recife &#8211; PE Brasil Embajador: Gabor de Zagon, C\u00f3nsul Tel\u00e9fono: (+55) 81 3035 4700 Fax: Email: consolato.recife@esteri.it Sitio web: consrecife.esteri.it\/consolato_recife\/it\/ Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13997,13296,13062],"tags":[12978],"class_list":["post-112225","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulados-en-brasil","category-consulados-italianos","category-italia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112225"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112225"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112225\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}