{"id":112183,"date":"2019-09-01T05:26:42","date_gmt":"2019-09-01T05:26:42","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-china-en-sao-paulo-brasil\/"},"modified":"2019-09-01T05:26:42","modified_gmt":"2019-09-01T05:26:42","slug":"consulado-general-de-china-en-sao-paulo-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-china-en-sao-paulo-brasil\/","title":{"rendered":"Consulado General de China en Sao Paulo, Brasil"},"content":{"rendered":"<div id=\"trave-2657167631\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado chino en Sao Paulo, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1071 Jardim America<br \/>\n01427-001 S\u00e3o Paulo &#8211; SP<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 11 3082 9877<br \/>\n(+55) 11-3082 9084<br \/>\n<strong>Fax:<\/strong> (+55) 11 3062 4396<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2833047182\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado chino en Sao Paulo, Brasil Direcci\u00f3n: 1071 Jardim America 01427-001 S\u00e3o Paulo &#8211; SP Brasil Embajador: Tel\u00e9fono: (+55) 11 3082 9877 (+55) 11-3082 9084 Fax: (+55) 11 3062 4396 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,5145,13658,13998],"tags":[12988],"class_list":["post-112183","post","type-post","status-publish","format-standard","hentry","category-brasil","category-china","category-consulado-general-de-china","category-consulado-general-en-brasil","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112183"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112183"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112183\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}