{"id":112167,"date":"2019-09-01T05:26:34","date_gmt":"2019-09-01T05:26:34","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-francia-en-campo-grande-brasil\/"},"modified":"2019-09-01T05:26:34","modified_gmt":"2019-09-01T05:26:34","slug":"consulado-de-francia-en-campo-grande-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-francia-en-campo-grande-brasil\/","title":{"rendered":"Consulado de Francia en Campo Grande, Brasil"},"content":{"rendered":"<div id=\"trave-3429788520\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado franc\u00e9s en Campo Grande, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua Antonio Maria Coelho, 1719<br \/>\n79002-221 Campo Grande MS<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mrs Aline Saddi Chaves, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) (67) 33 21 03 39<br \/>\n<strong>Fax:<\/strong> (+55) (67) 33 21 03 39<br \/>\n<strong>Email:<\/strong> chaves.aline@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1450365368\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado franc\u00e9s en Campo Grande, Brasil Direcci\u00f3n: Rua Antonio Maria Coelho, 1719 79002-221 Campo Grande MS Brasil Embajador: Mrs Aline Saddi Chaves, C\u00f3nsul Honorario Tel\u00e9fono: (+55) (67) 33 21 03 39 Fax: (+55) (67) 33 21 03 39 Email: chaves.aline@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13997,13518,13000],"tags":[12978],"class_list":["post-112167","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulados-en-brasil","category-consulados-franceses","category-francia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112167"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112167"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112167\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}