{"id":112165,"date":"2019-09-01T05:26:34","date_gmt":"2019-09-01T05:26:34","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-francia-en-belo-horizonte-brasil\/"},"modified":"2019-09-01T05:26:34","modified_gmt":"2019-09-01T05:26:34","slug":"consulado-de-francia-en-belo-horizonte-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-francia-en-belo-horizonte-brasil\/","title":{"rendered":"Consulado de Francia en Belo Horizonte, Brasil"},"content":{"rendered":"<div id=\"trave-1630671563\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado franc\u00e9s en Belo Horizonte, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAv.do Contorno 5417\/2 &#8211; Cruzeiro<br \/>\n30110-100 Belo Horizonte MG<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Manoel Bernardes, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong> (+55) (31) 4501 3601<br \/>\n<strong>Email:<\/strong> consulat.belohorizonte@yahoo.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2695058014\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado franc\u00e9s en Belo Horizonte, Brasil Direcci\u00f3n: Av.do Contorno 5417\/2 &#8211; Cruzeiro 30110-100 Belo Horizonte MG Brasil Embajador: Mr Manoel Bernardes, C\u00f3nsul Honorario Tel\u00e9fono: Fax: (+55) (31) 4501 3601 Email: consulat.belohorizonte@yahoo.fr Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13997,13518,13000],"tags":[12978],"class_list":["post-112165","post","type-post","status-publish","format-standard","hentry","category-brasil","category-consulados-en-brasil","category-consulados-franceses","category-francia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112165"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112165"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112165\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}