{"id":112123,"date":"2019-09-01T05:26:07","date_gmt":"2019-09-01T05:26:07","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-belgica-en-belo-horizonte-brasil\/"},"modified":"2019-09-01T05:26:07","modified_gmt":"2019-09-01T05:26:07","slug":"consulado-de-belgica-en-belo-horizonte-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-belgica-en-belo-horizonte-brasil\/","title":{"rendered":"Consulado de B\u00e9lgica en Belo Horizonte, Brasil"},"content":{"rendered":"<div id=\"trave-3670985197\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado belga en Belo Horizonte, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua Desembargador Jorge Fontana, 50<br \/>\nconjunto 1110 Belvedere<br \/>\n30320-670 Belo Horizonte &#8211; MG<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Henrique Machado Rabelo, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 31 3213-5554<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consulado.belgica.mg@terra.com.br<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2776391003\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado belga en Belo Horizonte, Brasil Direcci\u00f3n: Rua Desembargador Jorge Fontana, 50 conjunto 1110 Belvedere 30320-670 Belo Horizonte &#8211; MG Brasil Embajador: Henrique Machado Rabelo, C\u00f3nsul Honorario Tel\u00e9fono: (+55) 31 3213-5554 Fax: Email: consulado.belgica.mg@terra.com.br Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,13130,13142,13997],"tags":[12978],"class_list":["post-112123","post","type-post","status-publish","format-standard","hentry","category-belgica","category-brasil","category-consulados-belgas","category-consulados-en-brasil","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112123"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112123"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112123\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}