{"id":112079,"date":"2019-09-01T05:25:43","date_gmt":"2019-09-01T05:25:43","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-luxemburgo-en-brasilia-brasil\/"},"modified":"2019-09-01T05:25:43","modified_gmt":"2019-09-01T05:25:43","slug":"embajada-de-luxemburgo-en-brasilia-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-luxemburgo-en-brasilia-brasil\/","title":{"rendered":"Embajada de Luxemburgo en Brasilia, Brasil"},"content":{"rendered":"<div id=\"trave-290623269\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Luxemburgo en Brasilia, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSetor de Embaixadas Sul, QD 809<br \/>\n70422-900 Brasilia \/ DF<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) 61 3443 0072<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1238596902\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Luxemburgo en Brasilia, Brasil Direcci\u00f3n: Setor de Embaixadas Sul, QD 809 70422-900 Brasilia \/ DF Brasil Embajador: Tel\u00e9fono: (+55) 61 3443 0072 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13130,13775,13999,13474],"tags":[12975],"class_list":["post-112079","post","type-post","status-publish","format-standard","hentry","category-brasil","category-embajadas-de-luxemburgo","category-embajadas-en-brasil","category-luxemburgo","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112079"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112079"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112079\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}