{"id":112068,"date":"2019-09-01T05:25:34","date_gmt":"2019-09-01T05:25:34","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-alemania-en-blumenau-brasil\/"},"modified":"2019-09-01T05:25:34","modified_gmt":"2019-09-01T05:25:34","slug":"consulado-de-alemania-en-blumenau-brasil","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-alemania-en-blumenau-brasil\/","title":{"rendered":"Consulado de Alemania en Blumenau, Brasil"},"content":{"rendered":"<div id=\"trave-2057824969\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado alem\u00e1n en Blumenau, Brasil<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua Hermann Hering, 1<br \/>\nBairro Bom Retiro<br \/>\nCaixa Postal 1002<br \/>\n89010-600 Blumenau-SC<br \/>\nBrasil<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Hans-Dieter Didjurgeit, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+55) (47) 33 22 11 72<br \/>\n(+55) (47) 32 22 02 22<br \/>\n<strong>Fax:<\/strong> (+55) (47) 30 37 51 00<br \/>\n<strong>Email:<\/strong> blumenau@hk-diplo.de<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2273974264\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado alem\u00e1n en Blumenau, Brasil Direcci\u00f3n: Rua Hermann Hering, 1 Bairro Bom Retiro Caixa Postal 1002 89010-600 Blumenau-SC Brasil Embajador: Hans-Dieter Didjurgeit, C\u00f3nsul Honorario Tel\u00e9fono: (+55) (47) 33 22 11 72 (+55) (47) 32 22 02 22 Fax: (+55) (47) 30 37 51 00 Email: blumenau@hk-diplo.de Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,13130,13480,13997],"tags":[12978],"class_list":["post-112068","post","type-post","status-publish","format-standard","hentry","category-alemania","category-brasil","category-consulados-alemanes","category-consulados-en-brasil","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112068"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=112068"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/112068\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=112068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=112068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=112068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}