{"id":111786,"date":"2019-09-01T05:22:50","date_gmt":"2019-09-01T05:22:50","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-india-en-cotonu-benin\/"},"modified":"2019-09-01T05:22:50","modified_gmt":"2019-09-01T05:22:50","slug":"consulado-general-de-india-en-cotonu-benin","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-india-en-cotonu-benin\/","title":{"rendered":"Consulado General de India en Coton\u00fa, Benin"},"content":{"rendered":"<div id=\"trave-2021491436\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de India en Cotonou, Benin<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLote No.1430 R<br \/>\nVedoko Missogbe<br \/>\nCotonou<br \/>\nBenin<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Ashok R. Mirchandani, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+229) 97-974 502<br \/>\n(+229) 21-385 220<br \/>\n<strong>Fax:<\/strong> (+229) 21-380 724<br \/>\n<strong>Email:<\/strong> ashokmir@yahoo.com<br \/>\nindconsul.benin@sify.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-293417976\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de India en Cotonou, Benin Direcci\u00f3n: Lote No.1430 R Vedoko Missogbe Cotonou Benin Embajador: Ashok R. Mirchandani, C\u00f3nsul General Honorario Tel\u00e9fono: (+229) 97-974 502 (+229) 21-385 220 Fax: (+229) 21-380 724 Email: ashokmir@yahoo.com indconsul.benin@sify.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4948,13939,13004,5621],"tags":[12988],"class_list":["post-111786","post","type-post","status-publish","format-standard","hentry","category-benin","category-consulado-general-en-benin","category-consulado-general-indio","category-india","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111786"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111786"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111786\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}