{"id":111728,"date":"2019-09-01T05:22:15","date_gmt":"2019-09-01T05:22:15","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-cuba-en-cotonou-benin\/"},"modified":"2019-09-01T05:22:15","modified_gmt":"2019-09-01T05:22:15","slug":"embajada-de-cuba-en-cotonou-benin","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-cuba-en-cotonou-benin\/","title":{"rendered":"Embajada de Cuba en Cotonou, Benin"},"content":{"rendered":"<div id=\"trave-218870747\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Cuba en Cotonou, Benin<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nFrente al Hotel del Puerto<br \/>\nP.O.Box 948<br \/>\nCotonou 01<br \/>\nBenin<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+229) 21 31 52 97<br \/>\n<strong>Fax:<\/strong> (+229) 21 31 65 91<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1641984784\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Cuba en Cotonou, Benin Direcci\u00f3n: Frente al Hotel del Puerto P.O.Box 948 Cotonou 01 Benin Embajador: Tel\u00e9fono: (+229) 21 31 52 97 Fax: (+229) 21 31 65 91 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4948,5228,13327,13941],"tags":[12975],"class_list":["post-111728","post","type-post","status-publish","format-standard","hentry","category-benin","category-cuba","category-embajadas-cubanas","category-embajadas-en-benin","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111728"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111728"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111728\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}