{"id":111717,"date":"2019-09-01T05:22:09","date_gmt":"2019-09-01T05:22:09","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-las-bahamas-en-ciudad-de-belice-belice\/"},"modified":"2019-09-01T05:22:09","modified_gmt":"2019-09-01T05:22:09","slug":"consulado-de-las-bahamas-en-ciudad-de-belice-belice","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-las-bahamas-en-ciudad-de-belice-belice\/","title":{"rendered":"Consulado de las Bahamas en Ciudad de Belice, Belice"},"content":{"rendered":"<div id=\"trave-2156513922\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de las Bahamas en Ciudad de Belice, Belice<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1440 Coney Drive<br \/>\nP. O. Box 1730<br \/>\nCiudad de<br \/>\nBelice Belice<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+501) 223-2267<br \/>\n(+501) 227-7132 extension 139<br \/>\n<strong>Fax:<\/strong> (+501) 223-2389<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-472786937\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de las Bahamas en Ciudad de Belice, Belice Direcci\u00f3n: 1440 Coney Drive P. O. Box 1730 Ciudad de Belice Belice Embajador: Tel\u00e9fono: (+501) 223-2267 (+501) 227-7132 extension 139 Fax: (+501) 223-2389 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4875,13686,13552,13929],"tags":[12978],"class_list":["post-111717","post","type-post","status-publish","format-standard","hentry","category-bahamas","category-belice","category-consulados-de-las-bahamas","category-consulados-en-belice","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111717"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111717"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111717\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}