{"id":111705,"date":"2019-09-01T05:22:03","date_gmt":"2019-09-01T05:22:03","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-libano-en-ciudad-de-belice-belice\/"},"modified":"2019-09-01T05:22:03","modified_gmt":"2019-09-01T05:22:03","slug":"consulado-general-de-libano-en-ciudad-de-belice-belice","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-libano-en-ciudad-de-belice-belice\/","title":{"rendered":"Consulado General de L\u00edbano en Ciudad de Belice, Belice"},"content":{"rendered":"<div id=\"trave-1787924620\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado liban\u00e9s en Ciudad de Belice, Belice<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 297<br \/>\nCiudad de<br \/>\nBelice Belice<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+501) 222 &#8211; 4143<br \/>\n<strong>Fax:<\/strong> (+501) 222 &#8211; 4150<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-330312486\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado liban\u00e9s en Ciudad de Belice, Belice Direcci\u00f3n: PO Box 297 Ciudad de Belice Belice Embajador: Tel\u00e9fono: (+501) 222 &#8211; 4143 Fax: (+501) 222 &#8211; 4150 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13686,13931,13736,13373],"tags":[12988],"class_list":["post-111705","post","type-post","status-publish","format-standard","hentry","category-belice","category-consulado-general-en-belice","category-consulado-general-libanes","category-libano","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111705"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111705"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111705\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}