{"id":111640,"date":"2019-09-01T05:21:24","date_gmt":"2019-09-01T05:21:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-rusia-en-amberes-belgica\/"},"modified":"2019-09-01T05:21:24","modified_gmt":"2019-09-01T05:21:24","slug":"consulado-general-de-rusia-en-amberes-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-rusia-en-amberes-belgica\/","title":{"rendered":"Consulado General de Rusia en Amberes, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-2884709361\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado ruso en Amberes, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n20, Della Faillelaan<br \/>\n2020, Antwerpen<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Evgeny Egorov, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) (3) 829-1611<br \/>\n(+32) (3) 827-0464<br \/>\n<strong>Fax:<\/strong> (+32) (3) 829-0589<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> antwerpen.mid.ru<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3379487762\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado ruso en Amberes, B\u00e9lgica Direcci\u00f3n: 20, Della Faillelaan 2020, Antwerpen B\u00e9lgica Embajador: Evgeny Egorov, C\u00f3nsul General Tel\u00e9fono: (+32) (3) 829-1611 (+32) (3) 827-0464 Fax: (+32) (3) 829-0589 Email: Sitio web: antwerpen.mid.ru Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,13144,13868,12973],"tags":[12988],"class_list":["post-111640","post","type-post","status-publish","format-standard","hentry","category-belgica","category-consulado-general-de-rusia","category-consulado-general-en-belgica","category-rusia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111640"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111640"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111640\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}