{"id":111533,"date":"2019-09-01T05:20:21","date_gmt":"2019-09-01T05:20:21","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-argentina-en-bruselas-belgica\/"},"modified":"2019-09-01T05:20:21","modified_gmt":"2019-09-01T05:20:21","slug":"embajada-de-argentina-en-bruselas-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-argentina-en-bruselas-belgica\/","title":{"rendered":"Embajada de Argentina en Bruselas, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-3272624009\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada argentina en Bruselas, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nIxelles<br \/>\n1050 Bruselas<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) 2 647 78 12<br \/>\n<strong>Fax:<\/strong> (+32) 2 647 93 19<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Embajada: 09.00-18.00<br \/>\nConsulado: 09.00-14.00<\/p>\n<div id=\"trave-3265618078\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada argentina en Bruselas, B\u00e9lgica Direcci\u00f3n: Ixelles 1050 Bruselas B\u00e9lgica Embajador: Tel\u00e9fono: (+32) 2 647 78 12 Fax: (+32) 2 647 93 19 Email: Sitio web: Horas de oficina: Embajada: 09.00-18.00 Consulado: 09.00-14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4815,13141,13353,13872],"tags":[12975],"class_list":["post-111533","post","type-post","status-publish","format-standard","hentry","category-argentina","category-belgica","category-embajadas-argentinas","category-embajadas-en-belgica","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111533"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111533"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111533\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}