{"id":111519,"date":"2019-09-01T05:20:15","date_gmt":"2019-09-01T05:20:15","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-kirguistan-en-bruselas-belgica\/"},"modified":"2019-09-01T05:20:15","modified_gmt":"2019-09-01T05:20:15","slug":"embajada-de-kirguistan-en-bruselas-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-kirguistan-en-bruselas-belgica\/","title":{"rendered":"Embajada de Kirguist\u00e1n en Bruselas, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-2959612160\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Kirguist\u00e1n en Bruselas, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nIxelles<br \/>\n1050 Bruselas<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Asein Isaev, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) 2 640 01 31<br \/>\n(+32) 2 640 38 83<br \/>\n<strong>Fax:<\/strong> (+32) 2 640 01 31<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09:00 &#8211; 13:00<\/p>\n<div id=\"trave-3130125989\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Kirguist\u00e1n en Bruselas, B\u00e9lgica Direcci\u00f3n: Ixelles 1050 Bruselas B\u00e9lgica Embajador: Sr. Asein Isaev, Embajador Tel\u00e9fono: (+32) 2 640 01 31 (+32) 2 640 38 83 Fax: (+32) 2 640 01 31 Email: Sitio web: Horas de oficina: 09:00 &#8211; 13:00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,13156,13872,13155],"tags":[12975],"class_list":["post-111519","post","type-post","status-publish","format-standard","hentry","category-belgica","category-embajadas-de-kirguistan","category-embajadas-en-belgica","category-kirguistan","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111519"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111519"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111519\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}