{"id":111499,"date":"2019-09-01T05:20:03","date_gmt":"2019-09-01T05:20:03","guid":{"rendered":"https:\/\/travelqa.com\/oficina-de-representacion-de-macao-en-bruselas-belgica\/"},"modified":"2019-09-01T05:20:03","modified_gmt":"2019-09-01T05:20:03","slug":"oficina-de-representacion-de-macao-en-bruselas-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/oficina-de-representacion-de-macao-en-bruselas-belgica\/","title":{"rendered":"Oficina de representaci\u00f3n de Macao en Bruselas, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-164509154\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Oficina de Representaci\u00f3n de Macao en Bruselas, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1050 Bruselas<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) (2) 647 1265<br \/>\n<strong>Fax:<\/strong> (+32) (2) 640 1552<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3085607025\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Oficina de Representaci\u00f3n de Macao en Bruselas, B\u00e9lgica Direcci\u00f3n: 1050 Bruselas B\u00e9lgica Embajador: Tel\u00e9fono: (+32) (2) 647 1265 Fax: (+32) (2) 640 1552 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,11517,13877,13891],"tags":[12981],"class_list":["post-111499","post","type-post","status-publish","format-standard","hentry","category-belgica","category-macao","category-oficinas-de-representacion-en-belgica","category-oficinas-representativas-de-macao","tag-oficina-representativa"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111499"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111499"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111499\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}