{"id":111440,"date":"2019-09-01T05:19:23","date_gmt":"2019-09-01T05:19:23","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-senegal-en-lieja-belgica\/"},"modified":"2019-09-01T05:19:23","modified_gmt":"2019-09-01T05:19:23","slug":"consulado-de-senegal-en-lieja-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-senegal-en-lieja-belgica\/","title":{"rendered":"Consulado de Senegal en Lieja, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-1006128153\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado senegal\u00e9s en Liege, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRue Natalis 2<br \/>\n4020 Li\u00e8ge<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Laurent Minguet, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) 9 236 50 29<br \/>\n(+32) 495 230 006<br \/>\n<strong>Fax:<\/strong> (+32) 9 236 50 29<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Solo por cita<\/p>\n<div id=\"trave-3352174987\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado senegal\u00e9s en Liege, B\u00e9lgica Direcci\u00f3n: Rue Natalis 2 4020 Li\u00e8ge B\u00e9lgica Embajador: Laurent Minguet, C\u00f3nsul Honorario Tel\u00e9fono: (+32) 9 236 50 29 (+32) 495 230 006 Fax: (+32) 9 236 50 29 Email: Sitio web: Horas de oficina: Solo por cita<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,13867,13799,6440],"tags":[12978],"class_list":["post-111440","post","type-post","status-publish","format-standard","hentry","category-belgica","category-consulados-en-belgica","category-consulados-senegaleses","category-senegal","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111440"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111440"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111440\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}